{"id":9739,"date":"2026-07-12T04:35:57","date_gmt":"2026-07-12T04:35:57","guid":{"rendered":"https:\/\/omniumcultural.edu.mx\/site\/?p=9739"},"modified":"2026-07-12T04:35:57","modified_gmt":"2026-07-12T04:35:57","slug":"la-otan-ya-tiene-su-banco-el-dsrb","status":"publish","type":"post","link":"https:\/\/omniumcultural.edu.mx\/site\/2026\/07\/12\/la-otan-ya-tiene-su-banco-el-dsrb\/","title":{"rendered":"LA OTAN YA TIENE SU BANCO, EL DSRB"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Domingo 12 de julio de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Se desmarca de EEUU y enfrenta a Rusia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Armando Rojano Uscanga<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las guerras se hacen con dinero y arriesgando el f\u00edsico, de all\u00ed que no sorprenda que el resultando tangible de la reuni\u00f3n de la Organizaci\u00f3n del Tratado del Atl\u00e1ntico del Norte (OTAN) en Ankara, Turqu\u00eda, fuera la creaci\u00f3n del Banco para la Defensa, la Seguridad y la Resiliencia (DSRB), que movilizar\u00e1 134.000 millones de d\u00f3lares en pr\u00e9stamos y garant\u00edas para proyectos de defensa. Los accionistas son: Albania, B\u00e9lgica, Grecia, Letonia, Luxemburgo, Ruman\u00eda, Turqu\u00eda, Ucrania y Canad\u00e1 que ser\u00e1 la sede de la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los 32 estados miembros de la OTAN reiteraron su compromiso con la soberan\u00eda de Ucrania y que apoyar\u00e1n sus esfuerzos b\u00e9licos ante las agresiones rusas, con un pr\u00e9stamo de 80.000 millones de d\u00f3lares este a\u00f1o y una cantidad similar en 2027. Adem\u00e1s, Noruega destinar\u00e1 306 millones de d\u00f3lares a la compra de sistemas de defensa antia\u00e9rea Patriot para Ucrania, a trav\u00e9s del Priority Ukraine Requirements List (PURL), que permite a los aliados europeos y Canad\u00e1 financiar compras urgentes, principalmente a EEUU y del programa Jumpstart. Por su parte, Alemania financiar\u00e1 y producir\u00e1 en su territorio los misiles ucranianos Bars de largo alcance que usan plataformas no tripuladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La OTAN tiene ahora nuevas estructuras que fortalecen no solo a Ucrania, sino a toda Europa que se reconoce como seguro pr\u00f3ximo objetivo de Rusia y tiene recursos de los que puede disponer de inmediato, sin recurrir a EEUU que suele imponer condiciones inaceptables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Domingo 12 de julio de 2026 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Se desmarca de EEUU y enfrenta a Rusia Dr. Armando Rojano Uscanga Las guerras se hacen con dinero y arriesgando el f\u00edsico, de all\u00ed que no sorprenda que el resultando tangible de la reuni\u00f3n de la Organizaci\u00f3n del Tratado del Atl\u00e1ntico del Norte (OTAN) en Ankara,&#8230;<\/p>\n<p class=\"more-link\"><a href=\"https:\/\/omniumcultural.edu.mx\/site\/2026\/07\/12\/la-otan-ya-tiene-su-banco-el-dsrb\/\"><span>Read More<\/span><i>&#43;<\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9739","post","type-post","status-publish","format-standard","hentry","category-ahora-y-aqui"],"_links":{"self":[{"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/posts\/9739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/comments?post=9739"}],"version-history":[{"count":1,"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/posts\/9739\/revisions"}],"predecessor-version":[{"id":9740,"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/posts\/9739\/revisions\/9740"}],"wp:attachment":[{"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/media?parent=9739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/categories?post=9739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/omniumcultural.edu.mx\/site\/wp-json\/wp\/v2\/tags?post=9739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}